{"id":48,"date":"2021-08-26T00:28:47","date_gmt":"2021-08-26T00:28:47","guid":{"rendered":"http:\/\/localhost\/kloudstore\/?post_type=product&#038;p=48"},"modified":"2026-04-14T11:11:20","modified_gmt":"2026-04-14T11:11:20","slug":"windows-pro-10-oem-pack","status":"publish","type":"product","link":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/product\/windows-pro-10-oem-pack\/","title":{"rendered":"Windows Pro 10 OEM Pack"},"content":{"rendered":"<p>Windows\u00a010\u00a0Pro\u00a0includes all the features of\u00a0Windows\u00a010 Home, plus business functionality for encryption, remote log-in, creating virtual machines, and more<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Windows\u00a010\u00a0Pro\u00a0includes all the features of\u00a0Windows\u00a010 Home, plus business functionality for encryption, remote log-in, creating virtual machines, and more<\/p>\n","protected":false},"featured_media":69,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[21,18],"product_tag":[],"class_list":["post-48","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-box-pack","product_cat-software"],"_links":{"self":[{"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/product\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/comments?post=48"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/media\/69"}],"wp:attachment":[{"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/product_cat?post=48"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/demo.scorpiotechnologies.us\/kloudstore\/wp-json\/wp\/v2\/product_tag?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}